{"id":10147,"count":2,"description":"","link":"https:\/\/www.uitvconnect.com\/hindi\/tag\/%e0%a4%a5%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%a1%e0%a5%8d%e0%a4%b8\/","name":"\u0925\u094d\u0930\u0947\u0921\u094d\u0938","slug":"%e0%a4%a5%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%a1%e0%a5%8d%e0%a4%b8","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags\/10147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/posts?tags=10147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}