{"id":10372,"count":1,"description":"","link":"https:\/\/www.uitvconnect.com\/hindi\/tag\/%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%a4%e0%a4%bf%e0%a4%b0%e0%a5%8b%e0%a4%a7%e0%a5%80\/","name":"\u092a\u094d\u0930\u0924\u093f\u0930\u094b\u0927\u0940","slug":"%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%a4%e0%a4%bf%e0%a4%b0%e0%a5%8b%e0%a4%a7%e0%a5%80","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags\/10372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/posts?tags=10372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}