{"id":4390,"count":1,"description":"","link":"https:\/\/www.uitvconnect.com\/hindi\/tag\/%e0%a4%a8%e0%a4%bf%e0%a4%9c%e0%a5%80-%e0%a4%95%e0%a5%8d%e0%a4%b7%e0%a5%87%e0%a4%a4%e0%a5%8d%e0%a4%b0\/","name":"\u0928\u093f\u091c\u0940 \u0915\u094d\u0937\u0947\u0924\u094d\u0930","slug":"%e0%a4%a8%e0%a4%bf%e0%a4%9c%e0%a5%80-%e0%a4%95%e0%a5%8d%e0%a4%b7%e0%a5%87%e0%a4%a4%e0%a5%8d%e0%a4%b0","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags\/4390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/posts?tags=4390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}