{"id":4628,"count":1,"description":"","link":"https:\/\/www.uitvconnect.com\/hindi\/tag\/%e0%a4%95%e0%a4%82%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%8b%e0%a4%b2-%e0%a4%ab%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%95\/","name":"\u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u092b\u094d\u0930\u0940\u0915","slug":"%e0%a4%95%e0%a4%82%e0%a4%9f%e0%a5%8d%e0%a4%b0%e0%a5%8b%e0%a4%b2-%e0%a4%ab%e0%a5%8d%e0%a4%b0%e0%a5%80%e0%a4%95","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags\/4628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/posts?tags=4628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}