{"id":6215,"count":1,"description":"","link":"https:\/\/www.uitvconnect.com\/hindi\/tag\/%e0%a4%aa%e0%a4%a8%e0%a4%be%e0%a4%ae%e0%a4%be\/","name":"\u092a\u0928\u093e\u092e\u093e","slug":"%e0%a4%aa%e0%a4%a8%e0%a4%be%e0%a4%ae%e0%a4%be","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags\/6215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/posts?tags=6215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}