{"id":7234,"count":1,"description":"","link":"https:\/\/www.uitvconnect.com\/hindi\/tag\/%e0%a4%85%e0%a4%b5%e0%a4%a7%e0%a4%be%e0%a4%b0%e0%a4%a3%e0%a4%be\/","name":"\u0905\u0935\u0927\u093e\u0930\u0923\u093e","slug":"%e0%a4%85%e0%a4%b5%e0%a4%a7%e0%a4%be%e0%a4%b0%e0%a4%a3%e0%a4%be","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags\/7234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uitvconnect.com\/hindi\/wp-json\/wp\/v2\/posts?tags=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}